{"id":14655,"date":"2024-02-23T11:13:48","date_gmt":"2024-02-23T10:13:48","guid":{"rendered":"https:\/\/www.foebus.store\/?post_type=product&#038;p=14655"},"modified":"2025-07-30T14:50:32","modified_gmt":"2025-07-30T12:50:32","slug":"9620sa","status":"publish","type":"product","link":"https:\/\/www.foebus.de\/en\/product\/9620sa\/","title":{"rendered":"Brass slotted vents conical 0.3 ; 20mm \u00d8 ; rib-reinforced"},"content":{"rendered":"<p>Art.Nr.: 9620SA<br \/>\n\u00d8: 20mm<br \/>\nHeight: 7mm<br \/>\n1 rib<br \/>\nMindestmenge: 100 St\u00fcck<\/p>\n<p><a href=\"https:\/\/www.foebus.de\/en\/product\/stegamierte-messingschlitzduesen-konisch-03\/\">Return to Overview<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>9620SA \u00d8: 20mm 7mm 1 Steg 100 St\u00fcck Zur\u00fcck zur \u00dcbersicht<\/p>","protected":false},"featured_media":18542,"template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0"},"product_brand":[],"product_cat":[114],"product_tag":[],"class_list":{"0":"post-14655","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-messing-schlitzduesen-stegarmiert","8":"entry","9":"has-media","11":"first","12":"instock","13":"shipping-taxable","14":"product-type-simple","15":"has-product-nav","16":"col","17":"span_1_of_3","18":"owp-content-center","19":"owp-thumbs-layout-horizontal","20":"owp-btn-normal","21":"owp-tabs-layout-horizontal","22":"has-no-thumbnails"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Messingschlitzd\u00fcsen konisch 0,3 ; 20mm \u00d8 ; stegarmiert - F\u00f6bus<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.foebus.de\/en\/product\/9620sa\/\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Messingschlitzd\u00fcsen konisch 0,3 ; 20mm \u00d8 ; stegarmiert - F\u00f6bus\" \/>\n<meta name=\"twitter:description\" content=\"9620SA \u00d8: 20mm 7mm 1 Steg 100 St\u00fcck Zur\u00fcck zur \u00dcbersicht\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.foebus.de\/wp-content\/uploads\/2024\/02\/Messingduese-stegarmiert-20mm.png\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.foebus.de\\\/produkt\\\/9620sa\\\/\",\"url\":\"https:\\\/\\\/www.foebus.de\\\/produkt\\\/9620sa\\\/\",\"name\":\"Messingschlitzd\u00fcsen konisch 0,3 ; 20mm \u00d8 ; stegarmiert - F\u00f6bus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.foebus.store\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.foebus.de\\\/produkt\\\/9620sa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.foebus.de\\\/produkt\\\/9620sa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.foebus.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Messingduese-stegarmiert-20mm.png\",\"datePublished\":\"2024-02-23T10:13:48+00:00\",\"dateModified\":\"2025-07-30T12:50:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.foebus.de\\\/produkt\\\/9620sa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.foebus.de\\\/produkt\\\/9620sa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.foebus.de\\\/produkt\\\/9620sa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.foebus.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Messingduese-stegarmiert-20mm.png\",\"contentUrl\":\"https:\\\/\\\/www.foebus.de\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Messingduese-stegarmiert-20mm.png\",\"width\":633,\"height\":615},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.foebus.de\\\/produkt\\\/9620sa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.foebus.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.foebus.store\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Messingschlitzd\u00fcsen konisch 0,3 ; 20mm \u00d8 ; stegarmiert\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.foebus.store\\\/#website\",\"url\":\"https:\\\/\\\/www.foebus.store\\\/\",\"name\":\"F\u00f6bus\",\"description\":\"Welcome to the World of Foundry &amp; Patternmaking Supply.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.foebus.store\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.foebus.store\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.foebus.store\\\/#organization\",\"name\":\"Ludwig F\u00f6bus GmbH & Co KG\",\"url\":\"https:\\\/\\\/www.foebus.store\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.foebus.store\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.foebus.de\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/cropped-image004-1.png\",\"contentUrl\":\"https:\\\/\\\/www.foebus.de\\\/wp-content\\\/uploads\\\/2019\\\/01\\\/cropped-image004-1.png\",\"width\":432,\"height\":187,\"caption\":\"Ludwig F\u00f6bus GmbH & Co KG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.foebus.store\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Messingschlitzd\u00fcsen konisch 0,3 ; 20mm \u00d8 ; stegarmiert - F\u00f6bus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.foebus.de\/en\/product\/9620sa\/","twitter_card":"summary_large_image","twitter_title":"Messingschlitzd\u00fcsen konisch 0,3 ; 20mm \u00d8 ; stegarmiert - F\u00f6bus","twitter_description":"9620SA \u00d8: 20mm 7mm 1 Steg 100 St\u00fcck Zur\u00fcck zur \u00dcbersicht","twitter_image":"https:\/\/www.foebus.de\/wp-content\/uploads\/2024\/02\/Messingduese-stegarmiert-20mm.png","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.foebus.de\/produkt\/9620sa\/","url":"https:\/\/www.foebus.de\/produkt\/9620sa\/","name":"Messingschlitzd\u00fcsen konisch 0,3 ; 20mm \u00d8 ; stegarmiert - F\u00f6bus","isPartOf":{"@id":"https:\/\/www.foebus.store\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.foebus.de\/produkt\/9620sa\/#primaryimage"},"image":{"@id":"https:\/\/www.foebus.de\/produkt\/9620sa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.foebus.de\/wp-content\/uploads\/2024\/02\/Messingduese-stegarmiert-20mm.png","datePublished":"2024-02-23T10:13:48+00:00","dateModified":"2025-07-30T12:50:32+00:00","breadcrumb":{"@id":"https:\/\/www.foebus.de\/produkt\/9620sa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.foebus.de\/produkt\/9620sa\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.foebus.de\/produkt\/9620sa\/#primaryimage","url":"https:\/\/www.foebus.de\/wp-content\/uploads\/2024\/02\/Messingduese-stegarmiert-20mm.png","contentUrl":"https:\/\/www.foebus.de\/wp-content\/uploads\/2024\/02\/Messingduese-stegarmiert-20mm.png","width":633,"height":615},{"@type":"BreadcrumbList","@id":"https:\/\/www.foebus.de\/produkt\/9620sa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.foebus.de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.foebus.store\/shop\/"},{"@type":"ListItem","position":3,"name":"Messingschlitzd\u00fcsen konisch 0,3 ; 20mm \u00d8 ; stegarmiert"}]},{"@type":"WebSite","@id":"https:\/\/www.foebus.store\/#website","url":"https:\/\/www.foebus.store\/","name":"F\u00f6bus","description":"Welcome to the World of Foundry &amp; Patternmaking Supply.","publisher":{"@id":"https:\/\/www.foebus.store\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.foebus.store\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.foebus.store\/#organization","name":"Ludwig F\u00f6bus GmbH & Co KG","url":"https:\/\/www.foebus.store\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.foebus.store\/#\/schema\/logo\/image\/","url":"https:\/\/www.foebus.de\/wp-content\/uploads\/2019\/01\/cropped-image004-1.png","contentUrl":"https:\/\/www.foebus.de\/wp-content\/uploads\/2019\/01\/cropped-image004-1.png","width":432,"height":187,"caption":"Ludwig F\u00f6bus GmbH & Co KG"},"image":{"@id":"https:\/\/www.foebus.store\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.foebus.de\/en\/wp-json\/wp\/v2\/product\/14655","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.foebus.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.foebus.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.foebus.de\/en\/wp-json\/wp\/v2\/media\/18542"}],"wp:attachment":[{"href":"https:\/\/www.foebus.de\/en\/wp-json\/wp\/v2\/media?parent=14655"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.foebus.de\/en\/wp-json\/wp\/v2\/product_brand?post=14655"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.foebus.de\/en\/wp-json\/wp\/v2\/product_cat?post=14655"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.foebus.de\/en\/wp-json\/wp\/v2\/product_tag?post=14655"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}